{"id":760,"date":"2019-06-17T15:27:05","date_gmt":"2019-06-17T18:27:05","guid":{"rendered":"https:\/\/desenvolvimento.bravo.st\/hbb\/?p=760"},"modified":"2024-01-23T15:28:03","modified_gmt":"2024-01-23T18:28:03","slug":"oncologistas-do-hbb-participam-de-congresso-em-chicago","status":"publish","type":"post","link":"https:\/\/www.hbb.com.br\/site\/oncologistas-do-hbb-participam-de-congresso-em-chicago\/","title":{"rendered":"Oncologistas do HBB participam de congresso em Chicago"},"content":{"rendered":"<p>L\u00edvia Gravina e Leandro Brust acompanharam o congresso da Asco 2019, maior evento do mundo na \u00e1rea de Oncologia Cl\u00ednica<\/p>\n<p>Os m\u00e9dicos oncologistas do Hospital Bruno Born, L\u00edvia Brancher Gravina e Leandro Brust, participaram no in\u00edcio deste m\u00eas do Congresso da American Society of Clinical Oncology (Asco), em Chicago, nos Estados Unidos.<\/p>\n<p>O encontro da Sociedade Americana de Oncologia Cl\u00ednica \u00e9 considerado o maior congresso da \u00e1rea no mundo e este ano contou com a participa\u00e7\u00e3o de cerca de 40 mil profissionais. Durante o evento foram apresentados trabalhos com novidades para o tratamento de v\u00e1rios tipos de c\u00e2ncer.<\/p>\n<p>Segundo a m\u00e9dica L\u00edvia Gravina, destacam-se novos tratamentos para combater o c\u00e2ncer avan\u00e7ado de pr\u00f3stata, de p\u00e2ncreas e diferentes subtipos do c\u00e2ncer de mama. Al\u00e9m disso, a imunoterapia foi amplamente discutida e seu uso em combina\u00e7\u00e3o com quimioterapia agora passa a ser tratamento de escolha em c\u00e2ncer de cabe\u00e7a e pesco\u00e7o e c\u00e2ncer de mama triplo negativo quando avan\u00e7ados.<\/p>\n<p>No evento tamb\u00e9m foi enfatizada a import\u00e2ncia do diagn\u00f3stico molecular na oncologia, da investiga\u00e7\u00e3o de muta\u00e7\u00f5es que possam ser alvos para tratamentos e da consequente individualiza\u00e7\u00e3o do tratamento, o que leva a uma medicina cada vez mais personalizada para os pacientes oncol\u00f3gicos.<\/p>\n<p>\u201cA imunoterapia para o c\u00e2ncer de mama triplo negativo avan\u00e7ado j\u00e1 recebeu aprova\u00e7\u00e3o no Brasil pela Anvisa, e j\u00e1 nestes \u00faltimos dias logo ap\u00f3s o congresso, a imunoterapia para o tratamento do c\u00e2ncer de cabe\u00e7a e pesco\u00e7o avan\u00e7ado foi aprovada pela ag\u00eancia regulat\u00f3ria americana (FDA). Aguardamos por mais aprova\u00e7\u00f5es no nosso pa\u00eds nos pr\u00f3ximos meses e tamb\u00e9m j\u00e1 disponibilizamos alguns tratamentos de ponta atrav\u00e9s do nosso Centro de Pesquisa Cl\u00ednica em Oncologia, que tem expandido suas atividades de forma significativa\u201d, analisa. \u201cAtrav\u00e9s da pesquisa cl\u00ednica, muitos pacientes t\u00eam acesso a novas drogas (inclusive \u00e0 imunoterapia) que t\u00eam demonstrado \u00f3timos resultados. Aqui no HBB, a equipe de oncologistas est\u00e1 sempre em busca de atualiza\u00e7\u00f5es e qualifica\u00e7\u00e3o t\u00e9cnica para atender os nossos pacientes da melhor forma\u201d, ressalta a m\u00e9dica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00edvia Gravina e Leandro Brust acompanharam o congresso da Asco 2019, maior evento do mundo na \u00e1rea de Oncologia Cl\u00ednica Os m\u00e9dicos oncologistas do Hospital Bruno Born, L\u00edvia Brancher Gravina e Leandro Brust, participaram no in\u00edcio deste m\u00eas do Congresso\u2026<\/p>\n","protected":false},"author":1,"featured_media":761,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/760"}],"collection":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":1,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"predecessor-version":[{"id":762,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/760\/revisions\/762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media\/761"}],"wp:attachment":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/categories?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}