{"id":740,"date":"2019-09-11T15:16:49","date_gmt":"2019-09-11T18:16:49","guid":{"rendered":"https:\/\/desenvolvimento.bravo.st\/hbb\/?p=740"},"modified":"2024-01-23T15:17:23","modified_gmt":"2024-01-23T18:17:23","slug":"no-setembro-amarelo-atencao-aos-sinais-de-alerta","status":"publish","type":"post","link":"https:\/\/www.hbb.com.br\/site\/no-setembro-amarelo-atencao-aos-sinais-de-alerta\/","title":{"rendered":"No Setembro Amarelo, aten\u00e7\u00e3o aos sinais de alerta"},"content":{"rendered":"<p>M\u00eas \u00e9 dedicado \u00e0 preven\u00e7\u00e3o do suic\u00eddio, amea\u00e7a que ronda pessoas com depress\u00e3o e problemas psicol\u00f3gicos<\/p>\n<p>A cada 45 minutos, uma pessoa se suicida no Brasil. O dado, que tem como base levantamento do Senado, mostra a import\u00e2ncia e a necessidade de se prevenir mortes do g\u00eanero.<\/p>\n<p>\u00c9 este o objetivo da campanha Setembro Amarelo, que serve para difundir informa\u00e7\u00f5es importantes que possam auxiliar familiares e amigos de pessoas com problemas, e que tamb\u00e9m divulgam meios de apoio para pessoas que estejam sofrendo com pensamentos suicidas.<\/p>\n<p>O tema ainda \u00e9 tabu, mas a rede de apoio criada nos \u00faltimos anos tem ajudado a desmistificar o assunto.<\/p>\n<p>M\u00e9dico Psiquiatra do Hospital Bruno Born, de Lajeado, Bruno Lo Iacono Borba explica que o suic\u00eddio pode ocorrer a partir de diversos fatores \u2013 entre eles psicol\u00f3gicos, sociais, gen\u00e9ticos e culturais. \u201cO cen\u00e1rio em nossa regi\u00e3o (Vale do Taquari) mostra \u00edndices elevados de suic\u00eddio e tentativas, n\u00e3o s\u00f3 em adultos mas tamb\u00e9m em crian\u00e7as e adolescentes. E esta \u00e9 uma triste caracter\u00edstica mundial, onde o suic\u00eddio j\u00e1 \u00e9 a segunda principal causa de morte entre 15 e 29 anos. Um em cada seis jovens com idade entre 12 e 16 anos j\u00e1 pensou em suic\u00eddio\u201d, detalha.<\/p>\n<p>Especialista em Psiquiatria da Inf\u00e2ncia e Adolesc\u00eancia, Borba faz parte de uma equipe composta por m\u00e9dicos psiquiatras e neurologistas, psic\u00f3logos, enfermeiros, t\u00e9cnicos de enfermagem e terapeuta ocupacional. No HBB, o servi\u00e7o tamb\u00e9m disp\u00f5e de programa de forma\u00e7\u00e3o m\u00e9dica em psiquiatria e multidisciplinar em sa\u00fade.<\/p>\n<p><strong>Atendimento<\/strong><\/p>\n<p>A import\u00e2ncia de um atendimento diferenciado tem como resultado uma aten\u00e7\u00e3o especial do HBB com a sa\u00fade mental. O hospital disp\u00f5e de leitos para interna\u00e7\u00e3o (conv\u00eanios, particular e SUS) e atendimento ambulatorial via Central de Conv\u00eanios. Al\u00e9m disso, a equipe de psiquiatras do HBB est\u00e1 dispon\u00edvel para avalia\u00e7\u00f5es no Atendimento 24 Horas, todos os dias, inclusive finais de semana e feriados.<\/p>\n<p>Os profissionais s\u00e3o especializados em atender crian\u00e7as, adolescentes, adultos e idosos nos mais variados quadros de depress\u00e3o, ansiedade, dist\u00farbios do sono, depend\u00eancia qu\u00edmica, transtorno de d\u00e9ficit de aten\u00e7\u00e3o e hiperatividade (TDAH), bipolaridade, esquizofrenia, e outros.<\/p>\n<p>Mas Borba refor\u00e7a: \u201cA principal ajuda que algu\u00e9m pode oferecer a quem est\u00e1 pensando em suic\u00eddio \u00e9 a escuta, disponibilizar-se a um di\u00e1logo emp\u00e1tico, sem cr\u00edticas e julgamentos. E logo procurar atendimento no servi\u00e7o de sa\u00fade mais pr\u00f3ximo, para que seja avaliado o risco e encaminhado ao tratamento adequado.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00eas \u00e9 dedicado \u00e0 preven\u00e7\u00e3o do suic\u00eddio, amea\u00e7a que ronda pessoas com depress\u00e3o e problemas psicol\u00f3gicos A cada 45 minutos, uma pessoa se suicida no Brasil. O dado, que tem como base levantamento do Senado, mostra a import\u00e2ncia e a\u2026<\/p>\n","protected":false},"author":1,"featured_media":741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/740"}],"collection":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/comments?post=740"}],"version-history":[{"count":1,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/740\/revisions"}],"predecessor-version":[{"id":742,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/740\/revisions\/742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media\/741"}],"wp:attachment":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media?parent=740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/categories?post=740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}