{"id":705,"date":"2019-12-26T14:46:58","date_gmt":"2019-12-26T17:46:58","guid":{"rendered":"https:\/\/desenvolvimento.bravo.st\/hbb\/?p=705"},"modified":"2024-01-23T14:54:02","modified_gmt":"2024-01-23T17:54:02","slug":"surpresa-de-natal-para-os-pais-de-bebes-nas-utis-do-hbb","status":"publish","type":"post","link":"https:\/\/www.hbb.com.br\/site\/surpresa-de-natal-para-os-pais-de-bebes-nas-utis-do-hbb\/","title":{"rendered":"Surpresa de Natal para os pais de beb\u00eas nas UTIs do HBB"},"content":{"rendered":"<p>Uma a\u00e7\u00e3o diferente e pra l\u00e1 de emocionante marcou a manh\u00e3 de Natal nas UTIs Neonatal e Pedi\u00e1trica do Hospital Bruno Born : os beb\u00eas internados recepcionaram os pais vestidos com touquinhas de Papai Noel.<\/p>\n<p>A ideia surgiu dos pr\u00f3prios enfermeiros do setor, que buscavam meios para humanizar o atendimento em um dia t\u00e3o importante para as fam\u00edlias. \u201cConversamos com todos os respons\u00e1veis \u2013 m\u00e9dica coordenadora da UTI, N\u00e1talia Laste Beckenkamp Wald; com a gerente assistencial, Lidiane Stole; e com servi\u00e7o de Infec\u00e7\u00e3o do Hospital Bruno Born, e demos in\u00edcio \u00e0 prepara\u00e7\u00e3o\u201d, conta Giovana Johann Cortez, enfermeira coordenadora da UTI Neonatal e Pedi\u00e1trica. A partir da\u00ed, as touquinhas foram produzidas e higienizadas.<\/p>\n<p>\u201cOs pais tiveram uma grande surpresa ao chegar no leito e serem recebidos pelos filhos com a touquinha. Foi um momento muito especial: trouxe alegria e um pouco mais de conforto.\u201d<\/p>\n<p>Atualmente o HBB conta com seis leitos Neonatais e quatro Pedi\u00e1tricos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma a\u00e7\u00e3o diferente e pra l\u00e1 de emocionante marcou a manh\u00e3 de Natal nas UTIs Neonatal e Pedi\u00e1trica do Hospital Bruno Born : os beb\u00eas internados recepcionaram os pais vestidos com touquinhas de Papai Noel. A ideia surgiu dos pr\u00f3prios\u2026<\/p>\n","protected":false},"author":1,"featured_media":706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/705"}],"collection":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/comments?post=705"}],"version-history":[{"count":1,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/705\/revisions"}],"predecessor-version":[{"id":707,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/705\/revisions\/707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media\/706"}],"wp:attachment":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media?parent=705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/categories?post=705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}