{"id":697,"date":"2020-02-07T14:41:42","date_gmt":"2020-02-07T17:41:42","guid":{"rendered":"https:\/\/desenvolvimento.bravo.st\/hbb\/?p=697"},"modified":"2024-01-23T14:42:29","modified_gmt":"2024-01-23T17:42:29","slug":"doadores-de-coracao-salvam-vidas-de-dois-pacientes","status":"publish","type":"post","link":"https:\/\/www.hbb.com.br\/site\/doadores-de-coracao-salvam-vidas-de-dois-pacientes\/","title":{"rendered":"Doadores de cora\u00e7\u00e3o salvam vidas de dois pacientes"},"content":{"rendered":"<p>\u00d3rg\u00e3os foram captados nesta semana, em Lajeado. Rins e f\u00edgados tamb\u00e9m foram doados por fam\u00edlias dos pacientes<\/p>\n<p>Cora\u00e7\u00f5es, rins e f\u00edgados de dois jovens doadores ajudaram a salvar vidas, nesta semana. As capta\u00e7\u00f5es ocorreram no Hospital Bruno Born (HBB), em Lajeado. Em ambas as situa\u00e7\u00f5es equipes vieram para a cidade de helic\u00f3ptero auxiliar na retirada e no transporte dos \u00f3rg\u00e3os.<\/p>\n<p>Em meio ao luto, as fam\u00edlias aceitaram transformar a dor em esperan\u00e7a para quem tamb\u00e9m via a morte chegando. Por ser mais sens\u00edvel, o cora\u00e7\u00e3o \u00e9 um \u00f3rg\u00e3o dif\u00edcil de ser transplantado \u2013 por isso, apesar da dor da perda, a autoriza\u00e7\u00e3o das fam\u00edlias foi motivo de comemora\u00e7\u00e3o por parte das equipes que cuidam deste tipo de procedimento.<\/p>\n<p>\u201cSe n\u00e3o temos doadores, as listas de espera n\u00e3o andam e as filas aumentam cada vez mais. Tivemos seis diagn\u00f3sticos de morte encef\u00e1lica no HBB nos \u00faltimos quatro meses, e somente estas duas fam\u00edlias aceitaram que os \u00f3rg\u00e3os fossem transplantados\u201d, explica Adriana Calvi, enfermeira coordenadora da UTI do Bruno Born.<\/p>\n<p>Ao ser retirado, o cora\u00e7\u00e3o deve ser transplantado em at\u00e9 quatro horas \u2013 por isso a log\u00edstica em casos assim deve ser precisa. A Central de Transplantes e as equipes captadoras devem organizar-se para buscar, transportar e transplantar o \u00f3rg\u00e3o dentro deste prazo \u2013 f\u00edgado e rins tamb\u00e9m t\u00eam poucas horas para passarem pelo procedimento. \u201cNestes dois \u00faltimos casos as equipes vieram de helic\u00f3ptero para ganhar tempo. Na primeira capta\u00e7\u00e3o da semana a equipe se deslocou a Porto Alegre pela rodovia, ent\u00e3o foi necess\u00e1rio o uso de batedores para abrir caminho e chegar o mais r\u00e1pido poss\u00edvel\u201d, revela.<\/p>\n<p>O m\u00e9dico Intensivista Nelson Barbosa Franco, coordenador da OPO6 do HBB, explica que o hospital conta hoje com uma equipe de transplante renal \u2013 composta pelas m\u00e9dicas nefrologistas Nara Pimentel e Juliana Pimentel; pelos m\u00e9dicos urologistas Douglas Bohnemberger e Ernany Bender, e pelos cirurgi\u00f5es vasculares Gibran Ahmad e Vinicius Pletsch. Atualmente, no HBB s\u00e3o realizados apenas transplantes de rim e c\u00f3rneas. Transplantes de f\u00edgado, p\u00e2ncreas, combinado p\u00e2ncreas-rim, pulm\u00e3o ou cora\u00e7\u00e3o s\u00e3o feitos geralmente em centros de sa\u00fade maiores no Brasil.<\/p>\n<p>\u201cO maior desafio \u00e9 fazer com que a sociedade entenda, e aceite, que os \u00f3rg\u00e3os de seus familiares falecidos sejam doados. Em situa\u00e7\u00f5es em que o potencial doador de \u00f3rg\u00e3os falecido (que sofreu morte cerebral e encontra-se com os demais \u00f3rg\u00e3os mantidos apenas \u00e0s custas de suporte artificial, sem possibilidade nenhuma de revers\u00e3o), caber\u00e1 aos familiares mais pr\u00f3ximos decidir sobre o aceite ou a recusa da doa\u00e7\u00e3o de \u00f3rg\u00e3os. Na maioria das vezes os parentes s\u00e3o chamados a tomar uma decis\u00e3o important\u00edssima como essa logo ap\u00f3s o recebimento da not\u00edcia da morte, o que pode prejudicar este aceite. Precisamos que as pessoas compreendam a import\u00e2ncia deste ato para salvar a vida de outras.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00d3rg\u00e3os foram captados nesta semana, em Lajeado. Rins e f\u00edgados tamb\u00e9m foram doados por fam\u00edlias dos pacientes Cora\u00e7\u00f5es, rins e f\u00edgados de dois jovens doadores ajudaram a salvar vidas, nesta semana. As capta\u00e7\u00f5es ocorreram no Hospital Bruno Born (HBB), em\u2026<\/p>\n","protected":false},"author":1,"featured_media":698,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/697"}],"collection":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/comments?post=697"}],"version-history":[{"count":1,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/697\/revisions"}],"predecessor-version":[{"id":699,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/posts\/697\/revisions\/699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media\/698"}],"wp:attachment":[{"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/media?parent=697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hbb.com.br\/site\/wp-json\/wp\/v2\/categories?post=697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}